{"id":6607,"date":"2013-09-20T12:43:08","date_gmt":"2013-09-20T12:43:08","guid":{"rendered":"https:\/\/scitekconsultants.co.uk\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/"},"modified":"2022-08-16T08:43:43","modified_gmt":"2022-08-16T08:43:43","slug":"scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung","status":"publish","type":"post","link":"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/","title":{"rendered":"SCITEK unterst\u00fctzt ETI-Projekt zur sicheren Verwendung wasserstoffbasierter Brennstoffe bei der Stromerzeugung"},"content":{"rendered":"<p><span style=\"font-size: medium;\">Das Energy Technologies Institute (ETI) hat ein \u00a32 Millionen-Projekt ins Leben gerufen, das den sicheren Bau und Betrieb von Gasturbinen, Kolbenmotoren und Kraft-W\u00e4rme-Kopplungssystemen mit wasserstoffbasierten Brennstoffen vorantreiben soll. Das ETI ist eine \u00f6ffentlich-private Partnerschaft zwischen sechs globalen Industrieunternehmen &#8211; BP, Caterpillar, EDF, E.ON, Rolls-Royce und Shell &#8211; sowie der britischen Regierung. Ziel der Partnerschaft ist es, Technologien im \u201egro\u00dfen Ma\u00dfstab\u201c zu entwickeln, die dem Vereinigten K\u00f6nigreich helfen sollen, seine Energieziele f\u00fcr 2020 und 2050 zu erreichen.<\/span> <\/p>\n<p><span style=\"font-size: medium;\">Durch Modellierung und gro\u00df angelegte experimentelle Arbeit will das ETI-Projekt die Grenzen des sicheren Baus und Betriebs hocheffizienter Gas- und Dampfturbinen (GuD) und Kraft-W\u00e4rme-Kopplungssystemen (KWK) ermitteln, die mit einer Reihe von Brennstoffen mit hohen und variablen Wasserstoffkonzentrationen betrieben werden k\u00f6nnen.<\/span> <\/p>\n<p><span style=\"font-size: medium;\">Das Projekt zielt darauf ab, die Auswahl der Brennstoffe zu erweitern, die in Kraftwerken zur Strom- und W\u00e4rmeerzeugung auf sichere Weise verwendet werden k\u00f6nnen. Dies soll durch die folgenden Ma\u00dfnahmen erreicht werden:<\/span> <\/p>\n<ul>\n<li><span style=\"font-size: medium;\">Bestimmung der Grenzen des sicheren Baus und Betriebs von mit wasserstoffbasierten Brennstoffen betriebenen Stromerzeugungssystemen; und<\/span><\/li>\n<li><span style=\"font-size: medium;\">Identifizierung m\u00f6glicher Verbesserungen bei der detaillierten Auslegung und Instrumentierung von wasserstoffbasierten Stromerzeugungssystemen, um robustere und inh\u00e4rent sicherere Systemauslegungen zu erm\u00f6glichen.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: medium;\">Im Rahmen des ETI-Projekts ist SCITEK an der Entwicklung, Herstellung und Instrumentierung einer Versuchsanlage im verkleinerten Ma\u00dfstab mit einem kleinen Gasturbinentriebwerk (RR Viper 201) zur Bereitstellung eines Hei\u00dfgasstroms beteiligt.<\/span> <\/p>\n<p><span style=\"font-size: medium;\">SCITEK bewertete auch die Mischeigenschaften des geplanten Gasinjektionssystems mittels CFD-Modellierung von kompressiblen Hochtemperatur-Gasstrahlen im Gegenstrom mit Speziestransport.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Energy Technologies Institute (ETI) hat ein \u00a32 Millionen-Projekt ins Leben gerufen, das den sicheren Bau und Betrieb von Gasturbinen, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[32,33,34],"tags":[],"class_list":["post-6607","post","type-post","status-publish","format-standard","hentry","category-regelsysteme-und-instrumentierung","category-technische-analyse","category-technisches-design"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SCITEK unterst\u00fctzt ETI-Projekt zur sicheren Verwendung wasserstoffbasierter Brennstoffe bei der Stromerzeugung - SCITEK<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SCITEK unterst\u00fctzt ETI-Projekt zur sicheren Verwendung wasserstoffbasierter Brennstoffe bei der Stromerzeugung - SCITEK\" \/>\n<meta property=\"og:description\" content=\"Das Energy Technologies Institute (ETI) hat ein \u00a32 Millionen-Projekt ins Leben gerufen, das den sicheren Bau und Betrieb von Gasturbinen, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/\" \/>\n<meta property=\"og:site_name\" content=\"SCITEK\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-20T12:43:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-16T08:43:43+00:00\" \/>\n<meta name=\"author\" content=\"Damselfly Creative\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damselfly Creative\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\\\/\"},\"author\":{\"name\":\"Damselfly Creative\",\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/#\\\/schema\\\/person\\\/b702725dd4bf79c9e28b176bf8d6a9c4\"},\"headline\":\"SCITEK unterst\u00fctzt ETI-Projekt zur sicheren Verwendung wasserstoffbasierter Brennstoffe bei der Stromerzeugung\",\"datePublished\":\"2013-09-20T12:43:08+00:00\",\"dateModified\":\"2022-08-16T08:43:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\\\/\"},\"wordCount\":253,\"articleSection\":[\"Regelsysteme und Instrumentierung\",\"Technische Analyse\",\"Technisches Design\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\\\/\",\"url\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\\\/\",\"name\":\"SCITEK unterst\u00fctzt ETI-Projekt zur sicheren Verwendung wasserstoffbasierter Brennstoffe bei der Stromerzeugung - SCITEK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/#website\"},\"datePublished\":\"2013-09-20T12:43:08+00:00\",\"dateModified\":\"2022-08-16T08:43:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/#\\\/schema\\\/person\\\/b702725dd4bf79c9e28b176bf8d6a9c4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SCITEK unterst\u00fctzt ETI-Projekt zur sicheren Verwendung wasserstoffbasierter Brennstoffe bei der Stromerzeugung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/\",\"name\":\"SCITEK\",\"description\":\"Excellence in Engineering\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/#\\\/schema\\\/person\\\/b702725dd4bf79c9e28b176bf8d6a9c4\",\"name\":\"Damselfly Creative\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/wp-content\\\/litespeed\\\/avatar\\\/53977a0da9874047fa3b57034be8537e.jpg?ver=1778671993\",\"url\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/wp-content\\\/litespeed\\\/avatar\\\/53977a0da9874047fa3b57034be8537e.jpg?ver=1778671993\",\"contentUrl\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/wp-content\\\/litespeed\\\/avatar\\\/53977a0da9874047fa3b57034be8537e.jpg?ver=1778671993\",\"caption\":\"Damselfly Creative\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/dcadmin\"],\"url\":\"https:\\\/\\\/scitekconsultants.co.uk\\\/de\\\/author\\\/dcadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SCITEK unterst\u00fctzt ETI-Projekt zur sicheren Verwendung wasserstoffbasierter Brennstoffe bei der Stromerzeugung - SCITEK","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/","og_locale":"de_DE","og_type":"article","og_title":"SCITEK unterst\u00fctzt ETI-Projekt zur sicheren Verwendung wasserstoffbasierter Brennstoffe bei der Stromerzeugung - SCITEK","og_description":"Das Energy Technologies Institute (ETI) hat ein \u00a32 Millionen-Projekt ins Leben gerufen, das den sicheren Bau und Betrieb von Gasturbinen, [&hellip;]","og_url":"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/","og_site_name":"SCITEK","article_published_time":"2013-09-20T12:43:08+00:00","article_modified_time":"2022-08-16T08:43:43+00:00","author":"Damselfly Creative","twitter_misc":{"Verfasst von":"Damselfly Creative","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/#article","isPartOf":{"@id":"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/"},"author":{"name":"Damselfly Creative","@id":"https:\/\/scitekconsultants.co.uk\/de\/#\/schema\/person\/b702725dd4bf79c9e28b176bf8d6a9c4"},"headline":"SCITEK unterst\u00fctzt ETI-Projekt zur sicheren Verwendung wasserstoffbasierter Brennstoffe bei der Stromerzeugung","datePublished":"2013-09-20T12:43:08+00:00","dateModified":"2022-08-16T08:43:43+00:00","mainEntityOfPage":{"@id":"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/"},"wordCount":253,"articleSection":["Regelsysteme und Instrumentierung","Technische Analyse","Technisches Design"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/","url":"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/","name":"SCITEK unterst\u00fctzt ETI-Projekt zur sicheren Verwendung wasserstoffbasierter Brennstoffe bei der Stromerzeugung - SCITEK","isPartOf":{"@id":"https:\/\/scitekconsultants.co.uk\/de\/#website"},"datePublished":"2013-09-20T12:43:08+00:00","dateModified":"2022-08-16T08:43:43+00:00","author":{"@id":"https:\/\/scitekconsultants.co.uk\/de\/#\/schema\/person\/b702725dd4bf79c9e28b176bf8d6a9c4"},"breadcrumb":{"@id":"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/scitekconsultants.co.uk\/de\/scitek-unterstuetzt-eti-projekt-zur-sicheren-verwendung-wasserstoffbasierter-brennstoffe-bei-der-stromerzeugung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/scitekconsultants.co.uk\/de\/"},{"@type":"ListItem","position":2,"name":"SCITEK unterst\u00fctzt ETI-Projekt zur sicheren Verwendung wasserstoffbasierter Brennstoffe bei der Stromerzeugung"}]},{"@type":"WebSite","@id":"https:\/\/scitekconsultants.co.uk\/de\/#website","url":"https:\/\/scitekconsultants.co.uk\/de\/","name":"SCITEK","description":"Excellence in Engineering","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/scitekconsultants.co.uk\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/scitekconsultants.co.uk\/de\/#\/schema\/person\/b702725dd4bf79c9e28b176bf8d6a9c4","name":"Damselfly Creative","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/scitekconsultants.co.uk\/wp-content\/litespeed\/avatar\/53977a0da9874047fa3b57034be8537e.jpg?ver=1778671993","url":"https:\/\/scitekconsultants.co.uk\/wp-content\/litespeed\/avatar\/53977a0da9874047fa3b57034be8537e.jpg?ver=1778671993","contentUrl":"https:\/\/scitekconsultants.co.uk\/wp-content\/litespeed\/avatar\/53977a0da9874047fa3b57034be8537e.jpg?ver=1778671993","caption":"Damselfly Creative"},"sameAs":["https:\/\/x.com\/dcadmin"],"url":"https:\/\/scitekconsultants.co.uk\/de\/author\/dcadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/scitekconsultants.co.uk\/de\/wp-json\/wp\/v2\/posts\/6607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scitekconsultants.co.uk\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/scitekconsultants.co.uk\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/scitekconsultants.co.uk\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/scitekconsultants.co.uk\/de\/wp-json\/wp\/v2\/comments?post=6607"}],"version-history":[{"count":1,"href":"https:\/\/scitekconsultants.co.uk\/de\/wp-json\/wp\/v2\/posts\/6607\/revisions"}],"predecessor-version":[{"id":6722,"href":"https:\/\/scitekconsultants.co.uk\/de\/wp-json\/wp\/v2\/posts\/6607\/revisions\/6722"}],"wp:attachment":[{"href":"https:\/\/scitekconsultants.co.uk\/de\/wp-json\/wp\/v2\/media?parent=6607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/scitekconsultants.co.uk\/de\/wp-json\/wp\/v2\/categories?post=6607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scitekconsultants.co.uk\/de\/wp-json\/wp\/v2\/tags?post=6607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}